{"id":1655,"date":"2017-01-03T01:59:16","date_gmt":"2017-01-03T03:59:16","guid":{"rendered":"http:\/\/betomadureira.hospedagemdesites.ws\/bma\/?page_id=1655"},"modified":"2020-06-03T10:34:31","modified_gmt":"2020-06-03T13:34:31","slug":"quem-somos","status":"publish","type":"page","link":"http:\/\/www.betomadureira.com.br\/it\/quem-somos\/","title":{"rendered":"Chi Siamo"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" width=\"426\" height=\"640\" class=\"alignright wp-image-2540\" alt=\"Beto Madureira Ed Hardy\" src=\"http:\/\/www.betomadureira.com.br\/wp-content\/uploads\/2020\/06\/ed-hardy-interna7-681x1024.jpg\" srcset=\"http:\/\/www.betomadureira.com.br\/wp-content\/uploads\/2020\/06\/ed-hardy-interna7-681x1024.jpg 681w, http:\/\/www.betomadureira.com.br\/wp-content\/uploads\/2020\/06\/ed-hardy-interna7-200x300.jpg 200w, http:\/\/www.betomadureira.com.br\/wp-content\/uploads\/2020\/06\/ed-hardy-interna7-768x1154.jpg 768w, http:\/\/www.betomadureira.com.br\/wp-content\/uploads\/2020\/06\/ed-hardy-interna7-1022x1536.jpg 1022w, http:\/\/www.betomadureira.com.br\/wp-content\/uploads\/2020\/06\/ed-hardy-interna7-1363x2048.jpg 1363w, http:\/\/www.betomadureira.com.br\/wp-content\/uploads\/2020\/06\/ed-hardy-interna7-scaled.jpg 1703w\" sizes=\"(max-width: 426px) 100vw, 426px\" \/>L\u00b4 esperienza &nbsp;cumulata dal 1984, affiancata da un portfolio significativo, permette a Beto Madureira Arquitetura (BMA) creare e realizzare progetti con disegno preciso, in linea con il mercato, duraturi e con il miglior rapporto costo beneficio per i suoi clienti.<\/p>\n<p>Il disegno esatto e creativo dell\u00b4architetto Beto Madureira sempre conta e l\u00b4<em>expertise<\/em> &nbsp;alleato all\u00b4eccelenza nella realizzazione dei progetti garantisce il successo dell\u00b4impresa che lui amministra e controlla.<\/p>\n<p>La BMA ha il controllo dettagliato del bilancio preventivo e dei processi di realizzazione dell\u00b4opera, presentati con totale trasparenza ai clienti. Agisce in differenti tappe nelle sue realizzazioni \u2013 con lavori di grande, media e piccola portata \u2013 alla fine di produrre progetti&nbsp; sempre ispiratori per gli utenti e che presentano perfetta&nbsp; integrazione tra gli interventi realizzati ed il suo intorno in un\u00b4Architettura con armonia tra progetto, ambiente esterno e il pubblico che si intende ricevere.<\/p>\n<p>La BMA crede al potere del disegno plurale e democratico come soluzione alle sfide che devono essere vinte&nbsp;. Ogni progetto deve essere il risultato di una riflessione sul suo programma, il cliente e il contesto, per definere le sue caratteristiche specifiche senza prendersi a stili o modelli predefiniti. Il nostro oggettivo \u00e8 l\u00b4eccelenza nel disegno architettonico, partendo dalla diversit\u00e0 creativa, dal dialogo con il cliente, dal programma e dal contesto, in cui le idee sono il motore del progetto.<\/p>\n<p>In costante processo di espansione, la Beto Madureira Arquitetura possiede uffici a San Paolo, in Brasile, e a Firenze, in Italia.<\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>L\u00b4 esperienza &nbsp;cumulata dal 1984, affiancata da un portfolio significativo, permette a Beto Madureira Arquitetura (BMA) creare e realizzare progetti con disegno preciso, in linea con il mercato, duraturi e con il miglior rapporto costo beneficio per i suoi clienti. Il disegno esatto e creativo dell\u00b4architetto Beto Madureira sempre conta e l\u00b4expertise &nbsp;alleato all\u00b4eccelenza nella [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"ngg_post_thumbnail":0},"_links":{"self":[{"href":"http:\/\/www.betomadureira.com.br\/it\/wp-json\/wp\/v2\/pages\/1655"}],"collection":[{"href":"http:\/\/www.betomadureira.com.br\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/www.betomadureira.com.br\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/www.betomadureira.com.br\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.betomadureira.com.br\/it\/wp-json\/wp\/v2\/comments?post=1655"}],"version-history":[{"count":9,"href":"http:\/\/www.betomadureira.com.br\/it\/wp-json\/wp\/v2\/pages\/1655\/revisions"}],"predecessor-version":[{"id":2545,"href":"http:\/\/www.betomadureira.com.br\/it\/wp-json\/wp\/v2\/pages\/1655\/revisions\/2545"}],"wp:attachment":[{"href":"http:\/\/www.betomadureira.com.br\/it\/wp-json\/wp\/v2\/media?parent=1655"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}